{"id":1621,"date":"2017-03-30T15:58:33","date_gmt":"2017-03-30T13:58:33","guid":{"rendered":"http:\/\/neuro-spine-center.com.w0158a2a.kasserver.com\/nsc\/?page_id=1621"},"modified":"2026-07-01T09:20:36","modified_gmt":"2026-07-01T07:20:36","slug":"verwaltung","status":"publish","type":"page","link":"https:\/\/www.al-hami.de\/nsc\/ueber-uns\/abteilungen\/verwaltung\/","title":{"rendered":"Administration"},"content":{"rendered":"<div id='av-layout-grid-1' class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells    avia-builder-el-0  el_before_av_section  avia-builder-el-first  container_wrap sidebar_right' style=' '  >\n<div class=\"flex_cell no_margin av_one_half  avia-builder-el-1  el_before_av_cell_one_half  avia-builder-el-first   avia-full-stretch av-zero-padding \" style='height:500px; min-height:500px;vertical-align:middle; padding:0px; background-color:#19839a; '><div class='flex_cell_inner' ><\/div><\/div><div class=\"flex_cell no_margin av_one_half  avia-builder-el-2  el_after_av_cell_one_half  avia-builder-el-last   \" style='height:500px; min-height:500px;vertical-align:middle; padding:80px; background-color:#19839a; '><div class='flex_cell_inner' ><p><div style='padding-bottom:25px; color:#ffffff;font-size:34px;' class='av-special-heading av-special-heading-h3 custom-color-heading blockquote modern-quote  avia-builder-el-3  el_before_av_textblock  avia-builder-el-first  av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Administration<\/h3><div class='special-heading-border'><div class='special-heading-inner-border' style='border-color:#ffffff'><\/div><\/div><\/div><br \/>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  av_inherit_color '  style='color:#ffffff; '  itemprop=\"text\" ><p>Administration: Klinikmanagement, Finanz- und Personalverwaltung<\/p>\n<\/div><\/section><\/p>\n<\/div><\/div>\n<\/div>\n<div id='av_section_1' class='avia-section main_color avia-section-huge avia-no-border-styling avia-bg-style-scroll  avia-builder-el-5  el_after_av_layout_row  avia-builder-el-last   container_wrap sidebar_right' style=' '  ><div class='container' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1621'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-equal-height-column-flextable -flextable' style='margin-top:-200px; margin-bottom:0px; '><div class=\"flex_column av_one_third  no_margin flex_column_table_cell av-equal-height-column av-align-top first  avia-builder-el-6  el_before_av_one_third  avia-builder-el-first  \" style='padding:40px; border-radius:0px; '><\/div><div class=\"flex_column av_one_third  no_margin flex_column_table_cell av-equal-height-column av-align-top   avia-builder-el-7  el_after_av_one_third  el_before_av_one_third  \" style='padding:40px; background-color:#27a1bc; border-radius:0px; '><p><span class=\"av_font_icon avia_animate_when_visible avia-icon-animate  av-icon-style-  avia-icon-pos-center \" style=\"color:#ffffff; border-color:#ffffff;\"><span class='av-icon-char' style='font-size:60px;line-height:60px;' aria-hidden='true' data-av_icon='\uf111' data-av_iconfont='medical' ><\/span><\/span><br \/>\n<div style='height:20px' class='hr hr-invisible   avia-builder-el-9  el_after_av_font_icon  el_before_av_textblock '><span class='hr-inner ' ><span class='hr-inner-style'><\/span><\/span><\/div><br \/>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  av_inherit_color '  style='color:#ffffff; '  itemprop=\"text\" ><h4 style=\"text-align: center;\">Verwaltung<\/h4>\n<\/div><\/section><\/p><\/div><div class=\"flex_column av_one_third  no_margin flex_column_table_cell av-equal-height-column av-align-top   avia-builder-el-11  el_after_av_one_third  el_before_av_heading  \" style='padding:40px; border-radius:0px; '><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div style='padding-bottom:25px; font-size:34px;' class='av-special-heading av-special-heading-h3  blockquote modern-quote  avia-builder-el-12  el_after_av_one_third  el_before_av_one_fifth   av-inherit-size '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Unser Mitarbeiter der Administration<\/h3><div class='special-heading-border'><div class='special-heading-inner-border' ><\/div><\/div><\/div>\n<div class=\"flex_column av_one_fifth  flex_column_div av-zero-column-padding first  avia-builder-el-13  el_after_av_heading  el_before_av_one_fifth  \" style='border-radius:0px; '><section class='avia-team-member   avia-builder-el-14  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class='team-img-container'><img class='avia_image avia_image_team' src='https:\/\/www.al-hami.de\/nsc\/wp-content\/uploads\/Foto_Engel_Marleen-1-744x1030.jpg' alt='MARLEEN ENGEL'  itemprop=\"image\"  \/><\/div><h3 class='team-member-name'   itemprop=\"name\" >MARLEEN ENGEL<\/h3><div class='team-member-job-title '   itemprop=\"jobTitle\" >Gesch\u00e4ftsf\u00fchrerin<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >Neuro Spine Center GmbH<\/span><\/section><\/div><div class=\"flex_column av_one_fifth  flex_column_div av-zero-column-padding   avia-builder-el-15  el_after_av_one_fifth  el_before_av_one_fifth  \" style='border-radius:0px; '><section class='avia-team-member   avia-builder-el-16  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class='team-img-container'><img class='avia_image avia_image_team' src='https:\/\/www.al-hami.de\/nsc\/wp-content\/uploads\/mitarbeiter_schnell.jpg' alt='JUSTINA SCHNELL'  itemprop=\"image\"  \/><\/div><h3 class='team-member-name'   itemprop=\"name\" >JUSTINA SCHNELL<\/h3><div class='team-member-job-title '   itemprop=\"jobTitle\" >Administration \/ Finanzmanagement<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >Neuro Spine Center GmbH<\/span><\/section><\/div><div class=\"flex_column av_one_fifth  flex_column_div av-zero-column-padding   avia-builder-el-17  el_after_av_one_fifth  el_before_av_one_fifth  \" style='border-radius:0px; '><section class='avia-team-member   avia-builder-el-18  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class='team-img-container'><img class='avia_image avia_image_team' src='https:\/\/www.al-hami.de\/nsc\/wp-content\/uploads\/mitarbeiter_natascha-haas.jpg' alt='NATASCHA KL\u00dcBER'  itemprop=\"image\"  \/><\/div><h3 class='team-member-name'   itemprop=\"name\" >NATASCHA KL\u00dcBER<\/h3><div class='team-member-job-title '   itemprop=\"jobTitle\" >Administration \/ Finanzmanagement<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >Neuro Spine Center GmbH<\/span><\/section><\/div><div class=\"flex_column av_one_fifth  flex_column_div av-zero-column-padding   avia-builder-el-19  el_after_av_one_fifth  el_before_av_one_fifth  \" style='border-radius:0px; '><section class='avia-team-member   avia-builder-el-20  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class='team-img-container'><img class='avia_image avia_image_team' src='https:\/\/www.al-hami.de\/nsc\/wp-content\/uploads\/mitarbeiter_platzhalter-1-223x300.jpg' alt='KATRIN M\u00dcLLER'  itemprop=\"image\"  \/><\/div><h3 class='team-member-name'   itemprop=\"name\" >KATRIN M\u00dcLLER<\/h3><div class='team-member-job-title '   itemprop=\"jobTitle\" >Administration \/ Personalmanagement<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >Neuro Spine Center GmbH<\/span><\/section><\/div><div class=\"flex_column av_one_fifth  flex_column_div av-zero-column-padding   avia-builder-el-21  el_after_av_one_fifth  el_before_av_one_fifth  \" style='border-radius:0px; '><section class='avia-team-member   avia-builder-el-22  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class='team-img-container'><img class='avia_image avia_image_team av-team-img-original' src='https:\/\/www.al-hami.de\/nsc\/wp-content\/uploads\/johanna-brehl-223x300.png' alt='Johanna Sauer'  itemprop=\"image\"  \/><\/div><h3 class='team-member-name'   itemprop=\"name\" >Johanna Sauer<\/h3><div class='team-member-job-title '   itemprop=\"jobTitle\" >Administration \/ Finanzmanagement<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >Neuro Spine Center GmbH<\/span><\/section><\/div><div class=\"flex_column av_one_fifth  flex_column_div av-zero-column-padding first  avia-builder-el-23  el_after_av_one_fifth  avia-builder-el-last  column-top-margin\" style='border-radius:0px; '><section class='avia-team-member   avia-builder-el-24  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><div class='team-img-container'><img class='avia_image avia_image_team' src='https:\/\/www.al-hami.de\/nsc\/wp-content\/uploads\/DRNA-912x1030.jpg' alt='DR. NATALIA AL-HAMI'  itemprop=\"image\"  \/><\/div><h3 class='team-member-name'   itemprop=\"name\" >DR. NATALIA AL-HAMI<\/h3><div class='team-member-job-title '   itemprop=\"jobTitle\" >Mitgesch\u00e4ftsf\u00fchrerin der Dr. Al-Hami Holding GmbH<\/div><span class='hidden team-member-affiliation'  itemprop=\"affiliation\" >Neuro Spine Center GmbH<\/span><\/section><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1' class='main_color av_default_container_wrap container_wrap sidebar_right' style=' '  ><div class='container' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1621'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"parent":1535,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/pages\/1621"}],"collection":[{"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/comments?post=1621"}],"version-history":[{"count":90,"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/pages\/1621\/revisions"}],"predecessor-version":[{"id":6565,"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/pages\/1621\/revisions\/6565"}],"up":[{"embeddable":true,"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/pages\/1535"}],"wp:attachment":[{"href":"https:\/\/www.al-hami.de\/nsc\/wp-json\/wp\/v2\/media?parent=1621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}